{"id":12606,"date":"2022-09-05T13:24:45","date_gmt":"2022-09-05T12:24:45","guid":{"rendered":"https:\/\/chirp.co.uk\/newsletter\/mfb-68\/"},"modified":"2024-01-11T12:16:37","modified_gmt":"2024-01-11T12:16:37","slug":"mfb-68","status":"publish","type":"newsletter","link":"https:\/\/chirp.co.uk\/es\/newsletter\/mfb-68\/","title":{"rendered":"MFB 68"},"author":5,"featured_media":0,"parent":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"CBBTypography":[],"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[556,10],"sector":[298],"class_list":["post-12606","newsletter","type-newsletter","status-publish","hentry","category-general-maritime-es","category-maritime","sector-maritime-es-2"],"acf":{"edition":{"simple_value_formatted":"MFB 68","value_formatted":"MFB 68","value":"MFB 68","field":{"ID":1693,"key":"field_62b32b3052c0e","label":"Edition","name":"edition","aria-label":"","prefix":"acf","type":"text","value":null,"menu_order":0,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":1692,"wrapper":{"width":"","class":"","id":""},"wpml_cf_preferences":1,"user_roles":["administrator","editor","author","maritime_author","aviation_author"],"default_value":"","placeholder":"","prepend":"","append":"","maxlength":"","_name":"edition","_valid":1}},"editorial":{"simple_value_formatted":"<p>Lamentablemente, esta edici\u00f3n de FEEDBACK contiene varios informes con p\u00e9rdidas de vidas humanas. Nos recuerdan que no podemos relajar nuestra vigilancia, ni siquiera por un momento, porque las consecuencias pueden ser fatales. Toda muerte o lesi\u00f3n grave en el mar tiene repercusiones que van mucho m\u00e1s all\u00e1 del propio buque, sobre todo para los familiares y amigos cuyas vidas tambi\u00e9n se ven irremediablemente afectadas. As\u00ed que, por favor, mant\u00e9ngase alerta y haga todo lo posible para asegurarse de que llega a casa sano y salvo con su familia.<\/p>\n<p>Hay una serie de temas que recorren esta edici\u00f3n, y muchos de ellos ser\u00e1n deprimentemente familiares para nuestros lectores habituales. Los peligros de los trabajos en altura son bien conocidos y, sin embargo, los accidentes y las muertes siguen produci\u00e9ndose con frecuencia, como destacamos en las siguientes p\u00e1ginas. Del mismo modo, la importancia de garantizar la integridad de la estanqueidad durante el remolque puede parecer obvia, pero hemos recibido dos informes en los que se pas\u00f3 por alto el peligro, y pruebas de un organismo regulador de que el problema est\u00e1 bastante extendido.<\/p>\n<p>Los remolcadores son cada vez m\u00e1s potentes y sofisticados, pero hay muchas pruebas de que la formaci\u00f3n en el sector del remolque no est\u00e1 a la altura de los avances tecnol\u00f3gicos. \u00bfHa llegado el momento de que las autoridades mar\u00edtimas nacionales examinen m\u00e1s detenidamente la formaci\u00f3n de los remolcadores y los temas asociados, incluidos los requisitos para que los capitanes de barco con exenciones de pilotaje se familiaricen con las capacidades y limitaciones modernas de los remolcadores?<\/p>\n<p>El mal dise\u00f1o es otra caracter\u00edstica que aparece en varios de nuestros informes, pero con demasiada frecuencia aceptamos lo que nos dan y tratamos de sacar lo mejor de ello, en lugar de se\u00f1alar las deficiencias y exigir que se haga algo al respecto.<\/p>\n<p>Las buenas empresas siempre agradecer\u00e1n las opiniones de la flota, aunque algunos de nuestros informes sugieren que todav\u00eda hay empresas que se resisten a escuchar a sus tripulaciones o a gastar dinero en seguridad. Esto es decepcionante porque muchas otras industrias reconocen que la seguridad y la eficiencia van de la mano. Una empresa segura es una empresa m\u00e1s eficiente y rentable, y ya es hora de que m\u00e1s operadores mar\u00edtimos se den cuenta de ello.<\/p>\n<p>Por \u00faltimo, tenemos algunos informes en los que el funcionario que probablemente deber\u00eda haber estado supervisando un trabajo estaba haciendo el trabajo personalmente. Al eliminar el descuido de esta manera, queda un vac\u00edo evidente. \u00bfDispone de suficiente personal para realizar una supervisi\u00f3n adecuada en su barco?<\/p>\n<p>Hasta la pr\u00f3xima vez, \u00a1tenga cuidado ah\u00ed fuera!<\/p>\n","value_formatted":"Lamentablemente, esta edici\u00f3n de FEEDBACK contiene varios informes con p\u00e9rdidas de vidas humanas. Nos recuerdan que no podemos relajar nuestra vigilancia, ni siquiera por un momento, porque las consecuencias pueden ser fatales. Toda muerte o lesi\u00f3n grave en el mar tiene repercusiones que van mucho m\u00e1s all\u00e1 del propio buque, sobre todo para los familiares y amigos cuyas vidas tambi\u00e9n se ven irremediablemente afectadas. As\u00ed que, por favor, mant\u00e9ngase alerta y haga todo lo posible para asegurarse de que llega a casa sano y salvo con su familia.\n\nHay una serie de temas que recorren esta edici\u00f3n, y muchos de ellos ser\u00e1n deprimentemente familiares para nuestros lectores habituales. Los peligros de los trabajos en altura son bien conocidos y, sin embargo, los accidentes y las muertes siguen produci\u00e9ndose con frecuencia, como destacamos en las siguientes p\u00e1ginas. Del mismo modo, la importancia de garantizar la integridad de la estanqueidad durante el remolque puede parecer obvia, pero hemos recibido dos informes en los que se pas\u00f3 por alto el peligro, y pruebas de un organismo regulador de que el problema est\u00e1 bastante extendido.\n\nLos remolcadores son cada vez m\u00e1s potentes y sofisticados, pero hay muchas pruebas de que la formaci\u00f3n en el sector del remolque no est\u00e1 a la altura de los avances tecnol\u00f3gicos. \u00bfHa llegado el momento de que las autoridades mar\u00edtimas nacionales examinen m\u00e1s detenidamente la formaci\u00f3n de los remolcadores y los temas asociados, incluidos los requisitos para que los capitanes de barco con exenciones de pilotaje se familiaricen con las capacidades y limitaciones modernas de los remolcadores?\n\nEl mal dise\u00f1o es otra caracter\u00edstica que aparece en varios de nuestros informes, pero con demasiada frecuencia aceptamos lo que nos dan y tratamos de sacar lo mejor de ello, en lugar de se\u00f1alar las deficiencias y exigir que se haga algo al respecto.\n\nLas buenas empresas siempre agradecer\u00e1n las opiniones de la flota, aunque algunos de nuestros informes sugieren que todav\u00eda hay empresas que se resisten a escuchar a sus tripulaciones o a gastar dinero en seguridad. Esto es decepcionante porque muchas otras industrias reconocen que la seguridad y la eficiencia van de la mano. Una empresa segura es una empresa m\u00e1s eficiente y rentable, y ya es hora de que m\u00e1s operadores mar\u00edtimos se den cuenta de ello.\n\nPor \u00faltimo, tenemos algunos informes en los que el funcionario que probablemente deber\u00eda haber estado supervisando un trabajo estaba haciendo el trabajo personalmente. Al eliminar el descuido de esta manera, queda un vac\u00edo evidente. \u00bfDispone de suficiente personal para realizar una supervisi\u00f3n adecuada en su barco?\n\nHasta la pr\u00f3xima vez, \u00a1tenga cuidado ah\u00ed fuera!","value":"Lamentablemente, esta edici\u00f3n de FEEDBACK contiene varios informes con p\u00e9rdidas de vidas humanas. Nos recuerdan que no podemos relajar nuestra vigilancia, ni siquiera por un momento, porque las consecuencias pueden ser fatales. Toda muerte o lesi\u00f3n grave en el mar tiene repercusiones que van mucho m\u00e1s all\u00e1 del propio buque, sobre todo para los familiares y amigos cuyas vidas tambi\u00e9n se ven irremediablemente afectadas. As\u00ed que, por favor, mant\u00e9ngase alerta y haga todo lo posible para asegurarse de que llega a casa sano y salvo con su familia.\n\nHay una serie de temas que recorren esta edici\u00f3n, y muchos de ellos ser\u00e1n deprimentemente familiares para nuestros lectores habituales. Los peligros de los trabajos en altura son bien conocidos y, sin embargo, los accidentes y las muertes siguen produci\u00e9ndose con frecuencia, como destacamos en las siguientes p\u00e1ginas. Del mismo modo, la importancia de garantizar la integridad de la estanqueidad durante el remolque puede parecer obvia, pero hemos recibido dos informes en los que se pas\u00f3 por alto el peligro, y pruebas de un organismo regulador de que el problema est\u00e1 bastante extendido.\n\nLos remolcadores son cada vez m\u00e1s potentes y sofisticados, pero hay muchas pruebas de que la formaci\u00f3n en el sector del remolque no est\u00e1 a la altura de los avances tecnol\u00f3gicos. \u00bfHa llegado el momento de que las autoridades mar\u00edtimas nacionales examinen m\u00e1s detenidamente la formaci\u00f3n de los remolcadores y los temas asociados, incluidos los requisitos para que los capitanes de barco con exenciones de pilotaje se familiaricen con las capacidades y limitaciones modernas de los remolcadores?\n\nEl mal dise\u00f1o es otra caracter\u00edstica que aparece en varios de nuestros informes, pero con demasiada frecuencia aceptamos lo que nos dan y tratamos de sacar lo mejor de ello, en lugar de se\u00f1alar las deficiencias y exigir que se haga algo al respecto.\n\nLas buenas empresas siempre agradecer\u00e1n las opiniones de la flota, aunque algunos de nuestros informes sugieren que todav\u00eda hay empresas que se resisten a escuchar a sus tripulaciones o a gastar dinero en seguridad. Esto es decepcionante porque muchas otras industrias reconocen que la seguridad y la eficiencia van de la mano. Una empresa segura es una empresa m\u00e1s eficiente y rentable, y ya es hora de que m\u00e1s operadores mar\u00edtimos se den cuenta de ello.\n\nPor \u00faltimo, tenemos algunos informes en los que el funcionario que probablemente deber\u00eda haber estado supervisando un trabajo estaba haciendo el trabajo personalmente. Al eliminar el descuido de esta manera, queda un vac\u00edo evidente. \u00bfDispone de suficiente personal para realizar una supervisi\u00f3n adecuada en su barco?\n\nHasta la pr\u00f3xima vez, \u00a1tenga cuidado ah\u00ed fuera!","field":{"ID":1694,"key":"field_62b32b3052c56","label":"Editorial","name":"editorial","aria-label":"","prefix":"acf","type":"wysiwyg","value":null,"menu_order":1,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":1692,"wrapper":{"width":"","class":"","id":""},"wpml_cf_preferences":2,"default_value":"","tabs":"visual","toolbar":"full","media_upload":0,"delay":0,"_name":"editorial","_valid":1}},"sections":{"simple_value_formatted":null,"value_formatted":null,"value":false,"field":{"ID":1695,"key":"field_62b32b3052c97","label":"Sections","name":"sections","aria-label":"","prefix":"acf","type":"repeater","value":null,"menu_order":2,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":1692,"wrapper":{"width":"","class":"","id":""},"wpml_cf_preferences":2,"user_roles":["all"],"collapsed":"","min":0,"max":0,"layout":"block","button_label":"Add section","_name":"sections","_valid":1,"sub_fields":[{"ID":1696,"key":"field_62b32b3060607","label":"Section Title","name":"section_title","aria-label":"","prefix":"acf","type":"text","value":null,"menu_order":0,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":1695,"wrapper":{"width":"","class":"","id":""},"wpml_cf_preferences":2,"user_roles":["all"],"default_value":"","placeholder":"","prepend":"","append":"","maxlength":"","_name":"section_title","_valid":1,"parent_repeater":"field_62b32b3052c97"},{"ID":1697,"key":"field_62b32b3060648","label":"Section Copy","name":"section_copy","aria-label":"","prefix":"acf","type":"wysiwyg","value":null,"menu_order":1,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":1695,"wrapper":{"width":"","class":"","id":""},"wpml_cf_preferences":2,"user_roles":["all"],"default_value":"","tabs":"visual","toolbar":"full","media_upload":0,"delay":0,"_name":"section_copy","_valid":1,"parent_repeater":"field_62b32b3052c97"}],"rows_per_page":20}},"reports":{"simple_value_formatted":"<ul><li><a class=\"post-link\" href=\"https:\/\/chirp.co.uk\/es\/report\/m1987\/\" rel=\"bookmark\">M1987 (Es)<\/a><\/li><li><a class=\"post-link\" href=\"https:\/\/chirp.co.uk\/es\/report\/m1908\/\" rel=\"bookmark\">M1908 (Es)<\/a><\/li><li><a class=\"post-link\" href=\"https:\/\/chirp.co.uk\/es\/report\/m1983\/\" rel=\"bookmark\">M1983 (Es)<\/a><\/li><li><a class=\"post-link\" href=\"https:\/\/chirp.co.uk\/es\/report\/m2036\/\" rel=\"bookmark\">M2036<\/a><\/li><li><a class=\"post-link\" href=\"https:\/\/chirp.co.uk\/es\/report\/m1909\/\" rel=\"bookmark\">M1909 (Es)<\/a><\/li><li><a class=\"post-link\" href=\"https:\/\/chirp.co.uk\/es\/report\/m1895\/\" rel=\"bookmark\">M1895 (Es)<\/a><\/li><li><a class=\"post-link\" href=\"https:\/\/chirp.co.uk\/es\/report\/m1910\/\" rel=\"bookmark\">M1910 (Es)<\/a><\/li><li><a class=\"post-link\" href=\"https:\/\/chirp.co.uk\/es\/report\/m1900\/\" rel=\"bookmark\">M1900 (Es)<\/a><\/li><\/ul>","value_formatted":[12596,null,12619,12627,12629,12632,12634,12636,12638],"value":[12596,null,12619,12627,12629,12632,12634,12636,12638],"field":{"ID":1698,"key":"field_62b32b3052cd7","label":"Reports","name":"reports","aria-label":"","prefix":"acf","type":"post_object","value":null,"menu_order":3,"instructions":"Select reports to be featured in this edition of FEEDBACK","required":0,"id":"","class":"","conditional_logic":0,"parent":1692,"wrapper":{"width":"","class":"","id":""},"wpml_cf_preferences":2,"post_type":["report"],"taxonomy":"","allow_null":0,"multiple":1,"return_format":"id","ui":1,"_name":"reports","_valid":1,"bidirectional_target":[],"blockContexts":{"postType":"report","postIds":[12596,null,12619,12627,12629,12632,12634,12636,12638]}}},"pdf":{"simple_value_formatted":"<a href=\"https:\/\/chirp.co.uk\/app\/uploads\/2022\/09\/CHIRP-MFB-68-September-2022-English-edition-72dpi-RGB-for-online-1.pdf\" target=\"_blank\">CHIRP MFB 68 - September 2022 - English edition - 72dpi RGB - for online<\/a>","value_formatted":{"ID":13286,"id":13286,"url":"https:\/\/chirp.co.uk\/app\/uploads\/2022\/09\/CHIRP-MFB-68-September-2022-English-edition-72dpi-RGB-for-online-1.pdf","title":"CHIRP MFB 68 - September 2022 - English edition - 72dpi RGB - for online","alt":"","description":"","caption":"","mime_type":"application\/pdf","type":"application","subtype":"pdf","icon":"https:\/\/chirp.co.uk\/wp\/wp-includes\/images\/media\/document.png"},"value":13286,"field":{"ID":1699,"key":"field_62b32b3052d14","label":"Print Version PDF","name":"pdf","aria-label":"","prefix":"acf","type":"file","value":null,"menu_order":4,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":1692,"wrapper":{"width":"","class":"","id":""},"wpml_cf_preferences":2,"user_roles":["administrator","editor","author","maritime_author","aviation_author"],"return_format":"url","library":"all","min_size":"","max_size":"","mime_types":"","_name":"pdf","_valid":1}}},"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MFB 68 - CHIRP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chirp.co.uk\/es\/newsletter\/mfb-68\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MFB 68 - CHIRP\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chirp.co.uk\/es\/newsletter\/mfb-68\/\" \/>\n<meta property=\"og:site_name\" content=\"CHIRP\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-11T12:16:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chirp.co.uk\\\/es\\\/newsletter\\\/mfb-68\\\/\",\"url\":\"https:\\\/\\\/chirp.co.uk\\\/es\\\/newsletter\\\/mfb-68\\\/\",\"name\":\"MFB 68 - CHIRP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chirp.co.uk\\\/es\\\/#website\"},\"datePublished\":\"2022-09-05T12:24:45+00:00\",\"dateModified\":\"2024-01-11T12:16:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chirp.co.uk\\\/es\\\/newsletter\\\/mfb-68\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/chirp.co.uk\\\/es\\\/newsletter\\\/mfb-68\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chirp.co.uk\\\/es\\\/newsletter\\\/mfb-68\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chirp.co.uk\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Newsletters\",\"item\":\"https:\\\/\\\/chirp.co.uk\\\/es\\\/newsletter\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MFB 68\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chirp.co.uk\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/chirp.co.uk\\\/es\\\/\",\"name\":\"CHIRP\",\"description\":\"Confidential Human Factors Incident Reporting Programme\",\"publisher\":{\"@id\":\"https:\\\/\\\/chirp.co.uk\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/chirp.co.uk\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/chirp.co.uk\\\/es\\\/#organization\",\"name\":\"CHIRP\",\"url\":\"https:\\\/\\\/chirp.co.uk\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/chirp.co.uk\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/chirp.co.uk\\\/app\\\/uploads\\\/2024\\\/07\\\/chirp-logo-blue.svg\",\"contentUrl\":\"https:\\\/\\\/chirp.co.uk\\\/app\\\/uploads\\\/2024\\\/07\\\/chirp-logo-blue.svg\",\"caption\":\"CHIRP\"},\"image\":{\"@id\":\"https:\\\/\\\/chirp.co.uk\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MFB 68 - CHIRP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chirp.co.uk\/es\/newsletter\/mfb-68\/","og_locale":"es_ES","og_type":"article","og_title":"MFB 68 - CHIRP","og_url":"https:\/\/chirp.co.uk\/es\/newsletter\/mfb-68\/","og_site_name":"CHIRP","article_modified_time":"2024-01-11T12:16:37+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/chirp.co.uk\/es\/newsletter\/mfb-68\/","url":"https:\/\/chirp.co.uk\/es\/newsletter\/mfb-68\/","name":"MFB 68 - CHIRP","isPartOf":{"@id":"https:\/\/chirp.co.uk\/es\/#website"},"datePublished":"2022-09-05T12:24:45+00:00","dateModified":"2024-01-11T12:16:37+00:00","breadcrumb":{"@id":"https:\/\/chirp.co.uk\/es\/newsletter\/mfb-68\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chirp.co.uk\/es\/newsletter\/mfb-68\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/chirp.co.uk\/es\/newsletter\/mfb-68\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chirp.co.uk\/es\/"},{"@type":"ListItem","position":2,"name":"Newsletters","item":"https:\/\/chirp.co.uk\/es\/newsletter\/"},{"@type":"ListItem","position":3,"name":"MFB 68"}]},{"@type":"WebSite","@id":"https:\/\/chirp.co.uk\/es\/#website","url":"https:\/\/chirp.co.uk\/es\/","name":"CHIRP","description":"Confidential Human Factors Incident Reporting Programme","publisher":{"@id":"https:\/\/chirp.co.uk\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chirp.co.uk\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/chirp.co.uk\/es\/#organization","name":"CHIRP","url":"https:\/\/chirp.co.uk\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/chirp.co.uk\/es\/#\/schema\/logo\/image\/","url":"https:\/\/chirp.co.uk\/app\/uploads\/2024\/07\/chirp-logo-blue.svg","contentUrl":"https:\/\/chirp.co.uk\/app\/uploads\/2024\/07\/chirp-logo-blue.svg","caption":"CHIRP"},"image":{"@id":"https:\/\/chirp.co.uk\/es\/#\/schema\/logo\/image\/"}}]}},"wpml_current_locale":"es_ES","wpml_translations":[],"mfb_rest_fields":["title","yoast_head","yoast_head_json","wpml_current_locale","wpml_translations"],"_links":{"self":[{"href":"https:\/\/chirp.co.uk\/es\/wp-json\/wp\/v2\/newsletter\/12606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chirp.co.uk\/es\/wp-json\/wp\/v2\/newsletter"}],"about":[{"href":"https:\/\/chirp.co.uk\/es\/wp-json\/wp\/v2\/types\/newsletter"}],"author":[{"embeddable":true,"href":"https:\/\/chirp.co.uk\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/chirp.co.uk\/es\/wp-json\/wp\/v2\/comments?post=12606"}],"version-history":[{"count":0,"href":"https:\/\/chirp.co.uk\/es\/wp-json\/wp\/v2\/newsletter\/12606\/revisions"}],"acf:post":[{"embeddable":true,"href":"https:\/\/chirp.co.uk\/es\/wp-json\/wp\/v2\/report\/12638"},{"embeddable":true,"href":"https:\/\/chirp.co.uk\/es\/wp-json\/wp\/v2\/report\/12636"},{"embeddable":true,"href":"https:\/\/chirp.co.uk\/es\/wp-json\/wp\/v2\/report\/12634"},{"embeddable":true,"href":"https:\/\/chirp.co.uk\/es\/wp-json\/wp\/v2\/report\/12632"},{"embeddable":true,"href":"https:\/\/chirp.co.uk\/es\/wp-json\/wp\/v2\/report\/12629"},{"embeddable":true,"href":"https:\/\/chirp.co.uk\/es\/wp-json\/wp\/v2\/report\/12627"},{"embeddable":true,"href":"https:\/\/chirp.co.uk\/es\/wp-json\/wp\/v2\/report\/12619"},{"embeddable":true,"href":"https:\/\/chirp.co.uk\/es\/wp-json\/wp\/v2\/newsletter\/"},{"embeddable":true,"href":"https:\/\/chirp.co.uk\/es\/wp-json\/wp\/v2\/report\/12596"}],"wp:attachment":[{"href":"https:\/\/chirp.co.uk\/es\/wp-json\/wp\/v2\/media?parent=12606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chirp.co.uk\/es\/wp-json\/wp\/v2\/categories?post=12606"},{"taxonomy":"sector","embeddable":true,"href":"https:\/\/chirp.co.uk\/es\/wp-json\/wp\/v2\/sector?post=12606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}